{"id":11402,"date":"2022-07-13T15:51:39","date_gmt":"2022-07-13T13:51:39","guid":{"rendered":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/?page_id=11402"},"modified":"2022-07-13T15:51:44","modified_gmt":"2022-07-13T13:51:44","slug":"tandems","status":"publish","type":"page","link":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/tandems\/","title":{"rendered":"T\u00e1ndems"},"content":{"rendered":"<p>\u00bfQu\u00e9 es un t\u00e1ndem o intercambio ling\u00fc\u00edstico?<\/p>\n<p>Es una forma informal de aprender lenguas a trav\u00e9s de un intercambio ling\u00fc\u00edstico con otra persona que domina el idioma que se quiere practicar. Permite practicar y mejorar los conocimientos de un idioma y entrar en contacto con personas de otra cultura. Son unas sesiones de conversaci\u00f3n que cada pareja gestiona libremente. Es un complemento ideal al aprendizaje formal y se adapta a las necesidades y disponibilidad horaria de cada participante.<\/p>\n<p>\u00bfC\u00f3mo funciona?<\/p>\n<p>Es necesario que rellene un boleto que encontrar\u00e1 en la Biblioteca-CAM con su informaci\u00f3n (datos de contacto, intereses y disponibilidad). Cu\u00e9lgala en el panel que hemos habilitado como punto de encuentro. Se puede empezar en cualquier momento del curso. La idea es que regularmente consulte el panel y contacte con las personas que le gustar\u00eda formar un t\u00e1ndem y organice el primer encuentro. El t\u00e1ndem se puede encontrar d\u00f3nde y cu\u00e1ndo quiera. El per\u00edodo de la actividad se puede alargar como decida la pareja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es un t\u00e1ndem o intercambio ling\u00fc\u00edstico? Es una forma informal de aprender lenguas a trav\u00e9s de un intercambio ling\u00fc\u00edstico con otra persona que domina el idioma que se quiere practicar. Permite practicar y mejorar los conocimientos de un idioma y entrar en contacto con personas de otra cultura. Son unas sesiones de conversaci\u00f3n que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"page-templates\/side-menu.php","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11402","page","type-page","status-publish","hentry"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/pages\/11402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/comments?post=11402"}],"version-history":[{"count":1,"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/pages\/11402\/revisions"}],"predecessor-version":[{"id":11403,"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/pages\/11402\/revisions\/11403"}],"wp:attachment":[{"href":"https:\/\/agora-eoi.xtec.cat\/eoigirona\/wp-json\/wp\/v2\/media?parent=11402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}